{"id":1798,"date":"2019-03-15T12:28:56","date_gmt":"2019-03-15T11:28:56","guid":{"rendered":"https:\/\/rsu.gouv.ml\/portail\/?post_type=fw-portfolio&#038;p=1798"},"modified":"2019-03-15T12:41:54","modified_gmt":"2019-03-15T11:41:54","slug":"formation-sur-le-registre-social-unifie-rsu-du-programme-key","status":"publish","type":"fw-portfolio","link":"https:\/\/rsu.gouv.ml\/portail\/projets\/formation-sur-le-registre-social-unifie-rsu-du-programme-key\/","title":{"rendered":"Formation sur le Registre social unifi\u00e9 (RSU) du programme KEY"},"content":{"rendered":"<p>Du Mardi 12 au 14 mars 2019 s\u2019est tenu dans la salle de conf\u00e9rence de la Maison des partenariats Angers Bamako, un atelier de formation sur la plateforme RSU aux diff\u00e9rents membres du programme \u00ab\u00a0KEY\u00a0\u00bb<\/p>\n<h3>Le programme KEY<\/h3>\n<p>Le \u00ab Programme de renforcement de la r\u00e9silience \u00e0 l\u2019ins\u00e9curit\u00e9 alimentaire et nutritionnelle dans les r\u00e9gions au nord du Mali \u00bb appel\u00e9 KEY est mis en \u0153uvre dans les r\u00e9gions du centre et nord Mali \u00e0 travers cinq consortia emmen\u00e9s par HI, SOS Sahel, LVIA, CRS et AVSF. Le programme repose sur deux axes d\u2019intervention :<\/p>\n<ul>\n<li>Renforcer les capacit\u00e9s des communaut\u00e9s, des m\u00e9nages et des personnes les plus vuln\u00e9rables \u00e0 anticiper, absorber et se relever des chocs affectant leur s\u00e9curit\u00e9 alimentaire et nutritionnelle par la mise en \u0153uvre coordonn\u00e9e d\u2019actions de proximit\u00e9. Cet objectif correspond aux trois premiers piliers qui sont :\n<ul>\n<li><strong>Pilier 1 :<\/strong> Restaurer, renforcer et s\u00e9curiser les moyens d\u2019existence et am\u00e9liorer la protection sociale des communaut\u00e9s et m\u00e9nages vuln\u00e9rables ;<\/li>\n<li><strong>Pilier 2<\/strong> : Renforcer la nutrition des m\u00e9nages vuln\u00e9rables ;<\/li>\n<li><strong>Pilier 3<\/strong> : Renforcer durablement la productivit\u00e9 agricole et alimentaire, les revenus des plus vuln\u00e9rables et leur acc\u00e8s aux aliments.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li>Renforcer le r\u00f4le de leadership des autorit\u00e9s \u00e0 tous les \u00e9chelons dans la coordination, le suivi et l\u2019\u00e9valuation de l\u2019ensemble des interventions visant \u00e0 accro\u00eetre la r\u00e9silience des populations vuln\u00e9rables \u00e0 l\u2019ins\u00e9curit\u00e9 alimentaire et nutritionnelle. Cet objectif correspond au :\n<ul>\n<li><strong>Pilier 4 :<\/strong> Renforcer la gouvernance en mati\u00e8re de s\u00e9curit\u00e9 alimentaire et nutritionnelle.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Une des composantes de ce pilier est la coordination des interventions en mati\u00e8re de protection sociale afin d\u2019\u00e9viter les duplications d\u2019appuis. Cela passe par la constitution d\u2019une base de donn\u00e9es centralis\u00e9e qui est le RSU, \u00e0 travers laquelle on peut identifier les m\u00e9nages et le type d\u2019appuis qu\u2019ils re\u00e7oivent. C\u2019est pourquoi, le programme KEY entend alimenter le RSU en y reversant l\u2019ensemble des m\u00e9nages appuy\u00e9s au d\u2019intervention. Certains consortia comme ARC vont au-del\u00e0 du reversement de la liste des b\u00e9n\u00e9ficiaires renfor\u00e7ant les capacit\u00e9s et l\u2019accompagnement des DRDSES dans les r\u00e9gions de Gao, Tombouctou et Gao dans la mise en place du RSU et la coordination des activit\u00e9s y aff\u00e9rentes au niveau r\u00e9gional.<\/p>\n<p>Ainsi, \u00e0 travers de ses piliers 1 et 4, le programme KEY int\u00e8gre de fait la logique d\u00e9velopp\u00e9e par le RSU et son alimentation en donn\u00e9es est pr\u00e9vue en tant qu\u2019indicateur de r\u00e9sultat pour environ 20\u00a0000 m\u00e9nages b\u00e9n\u00e9ficiaires.<\/p>\n<p>La pr\u00e9sente formation a donc pour objectif de former les responsables techniques du programme KEY sur la nouvelle plateforme RSU. Les personnes form\u00e9es faciliteront \u00e0 leur tour la diffusion des connaissances et contenus au sein de leurs \u00e9quipes et des services techniques concern\u00e9s dans le but de conduire efficacement les enqu\u00eates.<\/p>\n<h3>Objectif de la formation<\/h3>\n<p>L\u2019objectif de cette formation est d\u2019amener les participants \u00e0 maitriser les diff\u00e9rentes composantes et fonctionnalit\u00e9s de la plateforme afin qu\u2019ils soient en capacit\u00e9 de r\u00e9pliquer la formation aupr\u00e8s de leurs \u00e9quipes.<\/p>\n<p>Plus sp\u00e9cifiquement il s\u2019agira de\u00a0:<\/p>\n<ul>\n<li>Comprendre la composante backoffice et son utilisation par l\u2019unit\u00e9 technique ;<\/li>\n<li>Comprendre le fonctionnement du site web et le mode de fourniture du contenu ;<\/li>\n<li>Maitriser les fonctionnalit\u00e9s de l\u2019espace priv\u00e9 pour les diff\u00e9rents profils ;<\/li>\n<li>Administrer le questionnaire RSU.<\/li>\n<\/ul>\n<h3>R\u00e9sultats attendus<\/h3>\n<p>Les r\u00e9sultats attendus sont les suivants\u00a0:<\/p>\n<ul>\n<li>La formation est mise en place\u00a0et permet de couvrir l\u2019ensemble des partenaires du programme KEY\u00a0;<\/li>\n<li>Les participants ma\u00eetrisent l\u2019ensemble des outils n\u00e9cessaires \u00e0 la formation de leurs \u00e9quipes et partenaires\u00a0;<\/li>\n<li>Un pack d\u2019outils est diffus\u00e9 parmi les participants\u00a0;<\/li>\n<li>Un compte rendu de formation est r\u00e9dig\u00e9\u00a0;<\/li>\n<li>Un support est propos\u00e9 pour la r\u00e9plication de la formation.<\/li>\n<\/ul>\n<h3>Participants<\/h3>\n<p>Les participants \u00e0 la formation sont les responsables techniques du programme KEY \u00e0 savoir les responsables de SE, les coordinateurs des programmes mais \u00e9galement les points focaux RSU au sein du consortium ARC. Les participants doivent avoir les capacit\u00e9s techniques n\u00e9cessaires \u00e0 appr\u00e9hender et \u00e0 r\u00e9pliquer la formation.<\/p>\n","protected":false},"featured_media":1799,"template":"","_links":{"self":[{"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/fw-portfolio\/1798"}],"collection":[{"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/fw-portfolio"}],"about":[{"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/types\/fw-portfolio"}],"version-history":[{"count":0,"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/fw-portfolio\/1798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/media\/1799"}],"wp:attachment":[{"href":"https:\/\/rsu.gouv.ml\/portail\/wp-json\/wp\/v2\/media?parent=1798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}